{"id":29279,"date":"2018-03-27T08:41:50","date_gmt":"2018-03-27T12:41:50","guid":{"rendered":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/?p=29279"},"modified":"2018-03-27T08:43:24","modified_gmt":"2018-03-27T12:43:24","slug":"una-bienvenida-con-sorpresas-diversas","status":"publish","type":"post","link":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/","title":{"rendered":"Una Bienvenida con Sorpresas Diversas"},"content":{"rendered":"<p>[et_pb_section bb_built=\u00bb1&#8243;][et_pb_row][et_pb_column type=\u00bb4_4&#8243;][et_pb_text _builder_version=\u00bb3.0.106&#8243; background_layout=\u00bblight\u00bb text_orientation=\u00bbjustified\u00bb]<\/p>\n<p>El d\u00eda jueves 22 del presente, el Colegio llev\u00f3 a cabo la recepci\u00f3n oficial de los nuevos apoderados que se incorporaron este a\u00f1o al proyecto educativo de nuestro establecimiento educacional. Este se realiz\u00f3 en el sal\u00f3n auditorio a eso de las 19,30  y cont\u00f3 con una masiva asistencia de los nuevos  papas. En la ocasi\u00f3n las m\u00e1ximas autoridades del Colegio, encabezadas por don Ferm\u00edn Roa Vallejos y miembros del Directorio, docentes directivos, la totalidad del cuerpo docente y paradocentes, dieron una cordial y fraternal bienvenida a los presentes.<\/p>\n<p>El encuentro cont\u00f3 con el discurso del Presidente de la Corporaci\u00f3n, don Ferm\u00edn Roa Vallejos, quien fue enf\u00e1tico en se\u00f1alar  que \u201cno basta con matricular a su hijo en el Colegio; es necesario tambi\u00e9n acompa\u00f1arlo  junto a sus profesores para obtener los resultados esperados pues as\u00ed y solo as\u00ed se logra explotar todas sus habilidades, destrezas y potencialidades, que en definitiva lo conducir\u00e1 a ser plenamente feliz\u201d.<\/p>\n<p> El encuentro fue dotado de una din\u00e1mica sinigual dada por las continuas intervenciones a cargo de los alumnos de quinto a\u00f1o \u201cb\u201d, quienes dirigidos por la profesora Verena Bielefeldt, representaron pasajes de la obra \u201cTodo sobre los padres e hijos\u201d, en los que se expon\u00edan situaciones de la vida cotidiana surgida de la convivencia entre \u00e9stos. Algunos de ellos versaron sobre los \u201ctipos de mamas\u201d, \u201cpadres desorientados\u201d, \u201cLa voz de la conciencia\u201d, \u201ctipos de hijos\u201d entre otros, que arrancaron carcajadas pues muchas de las puestas en escena obedec\u00edan a situaciones no muy alejadas de la realidad.<\/p>\n<p>Paralelo a estas peque\u00f1as intervenciones, tambi\u00e9n hubo dos  interesant\u00edsimas presentaciones de ingl\u00e9s  a cargo de las alumnas Francis Sandoval y  Josefa Mart\u00edn Salas, las que tuvieron por objetivo mostrar a los nuevos apoderados que esta asignatura no solo es transversal a  las mallas  curriculares de los diferentes niveles sino que tambi\u00e9n constituye uno de los pilares fundamentales de la ense\u00f1anza impartida por  nuestro Colegio, de manera tal de que nuestros alumnos egresen con un manejo avanzado del citado idioma.<\/p>\n<p>La m\u00fasica fue tambi\u00e9n otra de las \u00e1reas que tuvo  una magistral presentaci\u00f3n y donde los integrantes de la banda instrumental,  se lucieron con dos temas musicales que fueron ampliamente aplaudidos por los presentes dando con ello muestra de un reconocimiento impl\u00edcito y explicito al  excelente trabajo  expuesto. Particular reconocimiento hubo para el duo vocal compuesto por Consuelo Parra Nazal y Joaqu\u00edn Balboa Seguel, todos ellos dirigidos por  el profesor Felipe Flores S\u00e1ez.<\/p>\n<p>Todo lo anterior tuvo como objetivo demostrar  que el Colegio hace sus m\u00e1ximos esfuerzos por lograr  integrar todas las \u00e1reas del conocimiento y propender al desarrollo de las m\u00e1s diversas habilidades y destrezas   que poseen los alumnos de manera que cada uno de ellos tenga un espacio de desarrollo y crecimiento personal, que en definitiva lo convierta en un ser feliz consigo mismo y los dem\u00e1s.<\/p>\n<p>Tras ello, los padres y apoderados presentes pasaron a disfrutar de un coctel junto a todos los funcionarios del establecimiento, instancia que sirvi\u00f3 para conocerse e intercambiar vivencias y experiencias, que sin duda, ser\u00e1n parte del sustento desde el cual, nuestra instituci\u00f3n iniciar\u00e1 y proyectar\u00e1 su trabajo para hacer de sus hijos seres plenos y como ya se dijo, felices.<\/p>\n<p>[\/et_pb_text][et_pb_gallery _builder_version=\u00bb3.0.106&#8243; posts_number=\u00bb48&#8243; show_title_and_caption=\u00bboff\u00bb show_pagination=\u00bbon\u00bb gallery_ids=\u00bb29280,29281,29282,29283,29284,29285,29286,29287,29288,29289,29290,29291,29292,29293,29294,29295,29296,29297,29298,29299,29300,29301,29302,29303,29304,29305,29306,29307,29308&#8243; fullwidth=\u00bboff\u00bb orientation=\u00bblandscape\u00bb zoom_icon_color=\u00bb#008acc\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.9)\u00bb background_layout=\u00bblight\u00bb pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; custom_margin=\u00bb40px|||\u00bb \/][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda jueves 22 del presente, el Colegio llev\u00f3 a cabo la recepci\u00f3n oficial de los nuevos apoderados que se incorporaron este a\u00f1o al proyecto educativo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":29281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[87,3],"tags":[],"class_list":["post-29279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marzo-2018","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una Bienvenida con Sorpresas Diversas - Colegio Concepci\u00f3n Los \u00c1ngeles<\/title>\n<meta name=\"description\" content=\"&quot;FORMANDO L\u00cdDERES PARA EL FUTURO&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una Bienvenida con Sorpresas Diversas - Colegio Concepci\u00f3n Los \u00c1ngeles\" \/>\n<meta property=\"og:description\" content=\"&quot;FORMANDO L\u00cdDERES PARA EL FUTURO&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Concepci\u00f3n Los \u00c1ngeles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/colegioconcepcion.la\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/colegioconcepcion.la\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-27T12:41:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-27T12:43:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-content\/uploads\/2018\/03\/bienvenida-apoderados-02-2018-002.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CCLA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"CCLA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/\"},\"author\":{\"name\":\"CCLA\",\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/#\\\/schema\\\/person\\\/f7c6793d9d9dfc55972397c59429f143\"},\"headline\":\"Una Bienvenida con Sorpresas Diversas\",\"datePublished\":\"2018-03-27T12:41:50+00:00\",\"dateModified\":\"2018-03-27T12:43:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/\"},\"wordCount\":645,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/bienvenida-apoderados-02-2018-002.jpg\",\"articleSection\":[\"Marzo 2018\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/\",\"url\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/\",\"name\":\"Una Bienvenida con Sorpresas Diversas - Colegio Concepci\u00f3n Los \u00c1ngeles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/bienvenida-apoderados-02-2018-002.jpg\",\"datePublished\":\"2018-03-27T12:41:50+00:00\",\"dateModified\":\"2018-03-27T12:43:24+00:00\",\"description\":\"\\\"FORMANDO L\u00cdDERES PARA EL FUTURO\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/bienvenida-apoderados-02-2018-002.jpg\",\"contentUrl\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/bienvenida-apoderados-02-2018-002.jpg\",\"width\":675,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/una-bienvenida-con-sorpresas-diversas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una Bienvenida con Sorpresas Diversas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/\",\"name\":\"Colegio Concepci\u00f3n Los \u00c1ngeles\",\"description\":\"FORMANDO L\u00cdDERES PARA EL FUTURO\",\"publisher\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/#organization\"},\"alternateName\":\"CCLA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/#organization\",\"name\":\"Colegio Concepci\u00f3n Los \u00c1ngeles\",\"alternateName\":\"CCLA\",\"url\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/ccla-logo-75x.svg\",\"contentUrl\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/ccla-logo-75x.svg\",\"width\":1,\"height\":1,\"caption\":\"Colegio Concepci\u00f3n Los \u00c1ngeles\"},\"image\":{\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/colegioconcepcion.la\",\"https:\\\/\\\/www.instagram.com\\\/colegioconcepcion.la\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colegioconcepcionlosangeles.cl\\\/wp\\\/#\\\/schema\\\/person\\\/f7c6793d9d9dfc55972397c59429f143\",\"name\":\"CCLA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac994213e6a93af76823e079a287b14fe0698202befabf987b8f236c62be82ec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac994213e6a93af76823e079a287b14fe0698202befabf987b8f236c62be82ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac994213e6a93af76823e079a287b14fe0698202befabf987b8f236c62be82ec?s=96&d=mm&r=g\",\"caption\":\"CCLA\"},\"sameAs\":[\"https:\\\/\\\/colegiocncepcionlosangeles.cl\",\"https:\\\/\\\/www.facebook.com\\\/colegioconcepcion.la\",\"https:\\\/\\\/www.instagram.com\\\/colegioconcepcion.la\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una Bienvenida con Sorpresas Diversas - Colegio Concepci\u00f3n Los \u00c1ngeles","description":"\"FORMANDO L\u00cdDERES PARA EL FUTURO\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/","og_locale":"es_ES","og_type":"article","og_title":"Una Bienvenida con Sorpresas Diversas - Colegio Concepci\u00f3n Los \u00c1ngeles","og_description":"\"FORMANDO L\u00cdDERES PARA EL FUTURO\"","og_url":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/","og_site_name":"Colegio Concepci\u00f3n Los \u00c1ngeles","article_publisher":"https:\/\/www.facebook.com\/colegioconcepcion.la","article_author":"https:\/\/www.facebook.com\/colegioconcepcion.la","article_published_time":"2018-03-27T12:41:50+00:00","article_modified_time":"2018-03-27T12:43:24+00:00","og_image":[{"width":675,"height":450,"url":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-content\/uploads\/2018\/03\/bienvenida-apoderados-02-2018-002.jpg","type":"image\/jpeg"}],"author":"CCLA","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"CCLA","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/#article","isPartOf":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/"},"author":{"name":"CCLA","@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/#\/schema\/person\/f7c6793d9d9dfc55972397c59429f143"},"headline":"Una Bienvenida con Sorpresas Diversas","datePublished":"2018-03-27T12:41:50+00:00","dateModified":"2018-03-27T12:43:24+00:00","mainEntityOfPage":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/"},"wordCount":645,"commentCount":0,"publisher":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/#organization"},"image":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/#primaryimage"},"thumbnailUrl":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-content\/uploads\/2018\/03\/bienvenida-apoderados-02-2018-002.jpg","articleSection":["Marzo 2018","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/","url":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/","name":"Una Bienvenida con Sorpresas Diversas - Colegio Concepci\u00f3n Los \u00c1ngeles","isPartOf":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/#primaryimage"},"image":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/#primaryimage"},"thumbnailUrl":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-content\/uploads\/2018\/03\/bienvenida-apoderados-02-2018-002.jpg","datePublished":"2018-03-27T12:41:50+00:00","dateModified":"2018-03-27T12:43:24+00:00","description":"\"FORMANDO L\u00cdDERES PARA EL FUTURO\"","breadcrumb":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/#primaryimage","url":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-content\/uploads\/2018\/03\/bienvenida-apoderados-02-2018-002.jpg","contentUrl":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-content\/uploads\/2018\/03\/bienvenida-apoderados-02-2018-002.jpg","width":675,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/una-bienvenida-con-sorpresas-diversas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/"},{"@type":"ListItem","position":2,"name":"Una Bienvenida con Sorpresas Diversas"}]},{"@type":"WebSite","@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/#website","url":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/","name":"Colegio Concepci\u00f3n Los \u00c1ngeles","description":"FORMANDO L\u00cdDERES PARA EL FUTURO","publisher":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/#organization"},"alternateName":"CCLA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/#organization","name":"Colegio Concepci\u00f3n Los \u00c1ngeles","alternateName":"CCLA","url":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-content\/uploads\/2018\/03\/ccla-logo-75x.svg","contentUrl":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-content\/uploads\/2018\/03\/ccla-logo-75x.svg","width":1,"height":1,"caption":"Colegio Concepci\u00f3n Los \u00c1ngeles"},"image":{"@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/colegioconcepcion.la","https:\/\/www.instagram.com\/colegioconcepcion.la\/"]},{"@type":"Person","@id":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/#\/schema\/person\/f7c6793d9d9dfc55972397c59429f143","name":"CCLA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ac994213e6a93af76823e079a287b14fe0698202befabf987b8f236c62be82ec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac994213e6a93af76823e079a287b14fe0698202befabf987b8f236c62be82ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac994213e6a93af76823e079a287b14fe0698202befabf987b8f236c62be82ec?s=96&d=mm&r=g","caption":"CCLA"},"sameAs":["https:\/\/colegiocncepcionlosangeles.cl","https:\/\/www.facebook.com\/colegioconcepcion.la","https:\/\/www.instagram.com\/colegioconcepcion.la\/"]}]}},"_links":{"self":[{"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/posts\/29279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/comments?post=29279"}],"version-history":[{"count":0,"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/posts\/29279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/media\/29281"}],"wp:attachment":[{"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/media?parent=29279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/categories?post=29279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegioconcepcionlosangeles.cl\/wp\/wp-json\/wp\/v2\/tags?post=29279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}